{"id":2414,"count":1,"description":"","link":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/","name":"LEDOptics","slug":"ledoptics","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LEDOptics ar\u015fivleri - Component By \u00d6zdisan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LEDOptics ar\u015fivleri - Component By \u00d6zdisan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/\" \/>\n<meta property=\"og:site_name\" content=\"Component By \u00d6zdisan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/tag\\\/ledoptics\\\/\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/tag\\\/ledoptics\\\/\",\"name\":\"LEDOptics ar\u015fivleri - Component By \u00d6zdisan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/tag\\\/ledoptics\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/tag\\\/ledoptics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LEDOptics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/\",\"name\":\"Component By \u00d6zdisan\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#organization\",\"name\":\"Component By \u00d6zdisan\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/componentbyozdisan-logo.png\",\"contentUrl\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/componentbyozdisan-logo.png\",\"width\":508,\"height\":108,\"caption\":\"Component By \u00d6zdisan\"},\"image\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ozdisan\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LEDOptics ar\u015fivleri - Component By \u00d6zdisan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/","og_locale":"en_US","og_type":"article","og_title":"LEDOptics ar\u015fivleri - Component By \u00d6zdisan","og_url":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/","og_site_name":"Component By \u00d6zdisan","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/","url":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/","name":"LEDOptics ar\u015fivleri - Component By \u00d6zdisan","isPartOf":{"@id":"https:\/\/componentbyozdisan.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/componentbyozdisan.com\/en\/tag\/ledoptics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/componentbyozdisan.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"LEDOptics"}]},{"@type":"WebSite","@id":"https:\/\/componentbyozdisan.com\/en\/#website","url":"https:\/\/componentbyozdisan.com\/en\/","name":"Component By \u00d6zdisan","description":"","publisher":{"@id":"https:\/\/componentbyozdisan.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/componentbyozdisan.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/componentbyozdisan.com\/en\/#organization","name":"Component By \u00d6zdisan","url":"https:\/\/componentbyozdisan.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/componentbyozdisan.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/03\/componentbyozdisan-logo.png","contentUrl":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/03\/componentbyozdisan-logo.png","width":508,"height":108,"caption":"Component By \u00d6zdisan"},"image":{"@id":"https:\/\/componentbyozdisan.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ozdisan"]}]}},"_links":{"self":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/tags\/2414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/posts?tags=2414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}