{"id":27968,"date":"2024-10-15T17:27:26","date_gmt":"2024-10-15T14:27:26","guid":{"rendered":"https:\/\/componentbyozdisan.com\/?p=27968"},"modified":"2025-05-20T09:23:42","modified_gmt":"2025-05-20T06:23:42","slug":"nordic-nrf52840","status":"publish","type":"post","link":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/","title":{"rendered":"Nordic nRcF52840"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-bf1d842c868a84dc2a24b58f2cf6fb4e\"><strong>Nordic nRF52840 SoC (System On Chip)<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><a href=\"https:\/\/www.ozdisan.com\/p\/rf-entegre-cozumleri-7001?SearchText=NRF52840\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"760\" src=\"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-1024x760.jpg\" alt=\"Nordic NRF52840-1\" class=\"wp-image-19830\" style=\"width:197px;height:auto\" srcset=\"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-1024x760.jpg 1024w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-300x223.jpg 300w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-768x570.jpg 768w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-150x111.jpg 150w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-485x360.jpg 485w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-696x517.jpg 696w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1-1068x793.jpg 1068w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-NRF52840-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><div align=\"center\"><p>Review Now<\/p><\/div><\/figcaption><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading\"><strong>Features<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bluetooth 5 \/ Bluetooth Mesh \/ Thread \/ ZigBee \/ 2.4GHz \/ Ant<\/li>\n\n\n\n<li>USB Support<\/li>\n\n\n\n<li>32-bit ARM Cortex M4F processor with 64MHz speeds<\/li>\n\n\n\n<li>1MByte Flash \/ 256KByte Ram support<\/li>\n\n\n\n<li>FPU (Floating Point) \/ DSP\u00a0<\/li>\n\n\n\n<li>(Digital Signal Processing) support<\/li>\n\n\n\n<li>ARM TrustZone CryptoCell-310 cryptographic security support<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.ozdisan.com\/Category\/GetSearchCategoriesManufacture?MarkaID=NORDIC\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"163\" height=\"101\" src=\"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/08\/NORDIC.png\" alt=\"Nordic\" class=\"wp-image-13096\" style=\"width:131px;height:auto\" srcset=\"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/08\/NORDIC.png 163w, https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/08\/NORDIC-150x93.png 150w\" sizes=\"auto, (max-width: 163px) 100vw, 163px\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nordic nRF52840 SoC (System On Chip) Features<\/p>\n","protected":false},"author":1,"featured_media":19833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2400,1742,2146,2081],"tags":[2399,2237,2194],"class_list":["post-27968","post","type-post","status-publish","format-standard","has-post-thumbnail","category-11-issue","category-issues","category-rf-and-wireless-solutions","category-showroomen","tag-11-issues","tag-rfandwirelesssolutions","tag-showroom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nordic nRcF52840 - Component By \u00d6zdisan<\/title>\n<meta name=\"description\" content=\"Nordic nRcF52840\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nordic nRcF52840 - Component By \u00d6zdisan\" \/>\n<meta property=\"og:description\" content=\"Nordic nRcF52840\" \/>\n<meta property=\"og:url\" content=\"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/\" \/>\n<meta property=\"og:site_name\" content=\"Component By \u00d6zdisan\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T14:27:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T06:23:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-nRF52840-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"323\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yonetici\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yonetici\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/\"},\"author\":{\"name\":\"Yonetici\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#\\\/schema\\\/person\\\/b8881d213a434962c5d126ce57930fd3\"},\"headline\":\"Nordic nRcF52840\",\"datePublished\":\"2024-10-15T14:27:26+00:00\",\"dateModified\":\"2025-05-20T06:23:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nordic-nRF52840-2.jpg\",\"keywords\":[\"11. Issues\",\"RFandWirelessSolutions\",\"Showroom\"],\"articleSection\":[\"11. Issue\",\"Issues\",\"RF and Wireless Solutions\",\"Showroom\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/\",\"name\":\"Nordic nRcF52840 - Component By \u00d6zdisan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nordic-nRF52840-2.jpg\",\"datePublished\":\"2024-10-15T14:27:26+00:00\",\"dateModified\":\"2025-05-20T06:23:42+00:00\",\"description\":\"Nordic nRcF52840\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#primaryimage\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nordic-nRF52840-2.jpg\",\"contentUrl\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nordic-nRF52840-2.jpg\",\"width\":323,\"height\":323},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/nordic-nrf52840\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nordic nRcF52840\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/\",\"name\":\"Component By \u00d6zdisan\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#organization\",\"name\":\"Component By \u00d6zdisan\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/componentbyozdisan-logo.png\",\"contentUrl\":\"https:\\\/\\\/componentbyozdisan.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/componentbyozdisan-logo.png\",\"width\":508,\"height\":108,\"caption\":\"Component By \u00d6zdisan\"},\"image\":{\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ozdisan\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/#\\\/schema\\\/person\\\/b8881d213a434962c5d126ce57930fd3\",\"name\":\"Yonetici\",\"sameAs\":[\"http:\\\/\\\/componenttoproduction.com\"],\"url\":\"https:\\\/\\\/componentbyozdisan.com\\\/en\\\/author\\\/yonetici\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nordic nRcF52840 - Component By \u00d6zdisan","description":"Nordic nRcF52840","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/","og_locale":"en_US","og_type":"article","og_title":"Nordic nRcF52840 - Component By \u00d6zdisan","og_description":"Nordic nRcF52840","og_url":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/","og_site_name":"Component By \u00d6zdisan","article_published_time":"2024-10-15T14:27:26+00:00","article_modified_time":"2025-05-20T06:23:42+00:00","og_image":[{"width":323,"height":323,"url":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-nRF52840-2.jpg","type":"image\/jpeg"}],"author":"Yonetici","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Yonetici","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#article","isPartOf":{"@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/"},"author":{"name":"Yonetici","@id":"https:\/\/componentbyozdisan.com\/en\/#\/schema\/person\/b8881d213a434962c5d126ce57930fd3"},"headline":"Nordic nRcF52840","datePublished":"2024-10-15T14:27:26+00:00","dateModified":"2025-05-20T06:23:42+00:00","mainEntityOfPage":{"@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/"},"wordCount":48,"publisher":{"@id":"https:\/\/componentbyozdisan.com\/en\/#organization"},"image":{"@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#primaryimage"},"thumbnailUrl":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-nRF52840-2.jpg","keywords":["11. Issues","RFandWirelessSolutions","Showroom"],"articleSection":["11. Issue","Issues","RF and Wireless Solutions","Showroom"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/","url":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/","name":"Nordic nRcF52840 - Component By \u00d6zdisan","isPartOf":{"@id":"https:\/\/componentbyozdisan.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#primaryimage"},"image":{"@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#primaryimage"},"thumbnailUrl":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-nRF52840-2.jpg","datePublished":"2024-10-15T14:27:26+00:00","dateModified":"2025-05-20T06:23:42+00:00","description":"Nordic nRcF52840","breadcrumb":{"@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#primaryimage","url":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-nRF52840-2.jpg","contentUrl":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/10\/Nordic-nRF52840-2.jpg","width":323,"height":323},{"@type":"BreadcrumbList","@id":"https:\/\/componentbyozdisan.com\/en\/nordic-nrf52840\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/componentbyozdisan.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Nordic nRcF52840"}]},{"@type":"WebSite","@id":"https:\/\/componentbyozdisan.com\/en\/#website","url":"https:\/\/componentbyozdisan.com\/en\/","name":"Component By \u00d6zdisan","description":"","publisher":{"@id":"https:\/\/componentbyozdisan.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/componentbyozdisan.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/componentbyozdisan.com\/en\/#organization","name":"Component By \u00d6zdisan","url":"https:\/\/componentbyozdisan.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/componentbyozdisan.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/03\/componentbyozdisan-logo.png","contentUrl":"https:\/\/componentbyozdisan.com\/wp-content\/uploads\/2024\/03\/componentbyozdisan-logo.png","width":508,"height":108,"caption":"Component By \u00d6zdisan"},"image":{"@id":"https:\/\/componentbyozdisan.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ozdisan"]},{"@type":"Person","@id":"https:\/\/componentbyozdisan.com\/en\/#\/schema\/person\/b8881d213a434962c5d126ce57930fd3","name":"Yonetici","sameAs":["http:\/\/componenttoproduction.com"],"url":"https:\/\/componentbyozdisan.com\/en\/author\/yonetici\/"}]}},"_links":{"self":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/posts\/27968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/comments?post=27968"}],"version-history":[{"count":3,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/posts\/27968\/revisions"}],"predecessor-version":[{"id":27975,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/posts\/27968\/revisions\/27975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/media\/19833"}],"wp:attachment":[{"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/media?parent=27968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/categories?post=27968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/componentbyozdisan.com\/en\/wp-json\/wp\/v2\/tags?post=27968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}